{"id":9504,"date":"2021-10-22T10:06:13","date_gmt":"2021-10-22T10:06:13","guid":{"rendered":"https:\/\/volteco.com\/reference\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/"},"modified":"2022-09-12T09:08:08","modified_gmt":"2022-09-12T09:08:08","slug":"risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/","title":{"rendered":"Risanamento murature interne Ristorante Pizzeria Punto a Capo &#8211; San Secondo di Pinerolo &#8211; (TO)"},"content":{"rendered":"","protected":false},"featured_media":15135,"template":"","scope":[1119],"problem":[],"country":[1195,1198],"building":[34],"class_list":["post-9504","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-risanamento-umidita-murature","country-italia","country-piemonte","building-pubblico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risanamento murature interne Ristorante Pizzeria Punto a Capo - San Secondo di Pinerolo - (TO) | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne Ristorante Pizzeria Punto a Capo, San Secondo di Pinerolo, (TO).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risanamento murature interne Ristorante Pizzeria Punto a Capo - San Secondo di Pinerolo - (TO) | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne Ristorante Pizzeria Punto a Capo, San Secondo di Pinerolo, (TO).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:08:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/img-20200824-wa0007_0-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"714\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/\",\"name\":\"Risanamento murature interne Ristorante Pizzeria Punto a Capo - San Secondo di Pinerolo - (TO) | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/img-20200824-wa0007_0-1.jpg\",\"datePublished\":\"2021-10-22T10:06:13+00:00\",\"dateModified\":\"2022-09-12T09:08:08+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne Ristorante Pizzeria Punto a Capo, San Secondo di Pinerolo, (TO).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/img-20200824-wa0007_0-1.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/img-20200824-wa0007_0-1.jpg\",\"width\":714,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Risanamento murature interne Ristorante Pizzeria Punto a Capo &#8211; San Secondo di Pinerolo &#8211; (TO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risanamento murature interne Ristorante Pizzeria Punto a Capo - San Secondo di Pinerolo - (TO) | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne Ristorante Pizzeria Punto a Capo, San Secondo di Pinerolo, (TO).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/","og_locale":"it_IT","og_type":"article","og_title":"Risanamento murature interne Ristorante Pizzeria Punto a Capo - San Secondo di Pinerolo - (TO) | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne Ristorante Pizzeria Punto a Capo, San Secondo di Pinerolo, (TO).","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-09-12T09:08:08+00:00","og_image":[{"width":714,"height":430,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/img-20200824-wa0007_0-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/","name":"Risanamento murature interne Ristorante Pizzeria Punto a Capo - San Secondo di Pinerolo - (TO) | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/img-20200824-wa0007_0-1.jpg","datePublished":"2021-10-22T10:06:13+00:00","dateModified":"2022-09-12T09:08:08+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne Ristorante Pizzeria Punto a Capo, San Secondo di Pinerolo, (TO).","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/img-20200824-wa0007_0-1.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/img-20200824-wa0007_0-1.jpg","width":714,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-ristorante-pizzeria-punto-a-capo-san-secondo-di-pinerolo-to\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Risanamento murature interne Ristorante Pizzeria Punto a Capo &#8211; San Secondo di Pinerolo &#8211; (TO)"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/9504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/15135"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=9504"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=9504"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=9504"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=9504"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=9504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}