{"id":9380,"date":"2021-10-22T10:05:34","date_gmt":"2021-10-22T10:05:34","guid":{"rendered":"https:\/\/volteco.com\/reference\/protezione-impermeabile-massetti-edificio-pescara-pe\/"},"modified":"2023-10-20T15:12:17","modified_gmt":"2023-10-20T15:12:17","slug":"protezione-impermeabile-massetti-edificio-pescara-pe","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/","title":{"rendered":"Protezione Impermeabile Massetti Edificio &#8211; Pescara &#8211; PE"},"content":{"rendered":"","protected":false},"featured_media":15075,"template":"","scope":[1117],"problem":[748,1132,1131],"country":[1195,1205],"building":[34],"class_list":["post-9380","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-terrazzi-e-balconi","problem-fessurazioni-soluzioni","problem-efflorescenze-su-piastrella","problem-pavimenti-danneggiati-da-gelo-e-disgelo","country-italia","country-abruzzo","building-pubblico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protezione Impermeabile Massetti Edificio - Pescara - PE | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Protezione Impermeabile Massetti Edificio, Pescara, PE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protezione Impermeabile Massetti Edificio - Pescara - PE | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Protezione Impermeabile Massetti Edificio, Pescara, PE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T15:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/protezionebancodinapoli-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/\",\"name\":\"Protezione Impermeabile Massetti Edificio - Pescara - PE | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/protezionebancodinapoli-1-scaled.jpg\",\"datePublished\":\"2021-10-22T10:05:34+00:00\",\"dateModified\":\"2023-10-20T15:12:17+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Protezione Impermeabile Massetti Edificio, Pescara, PE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/protezionebancodinapoli-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/protezionebancodinapoli-1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/protezione-impermeabile-massetti-edificio-pescara-pe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Protezione Impermeabile Massetti Edificio &#8211; Pescara &#8211; PE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protezione Impermeabile Massetti Edificio - Pescara - PE | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Protezione Impermeabile Massetti Edificio, Pescara, PE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/","og_locale":"it_IT","og_type":"article","og_title":"Protezione Impermeabile Massetti Edificio - Pescara - PE | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Protezione Impermeabile Massetti Edificio, Pescara, PE.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2023-10-20T15:12:17+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/protezionebancodinapoli-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/","name":"Protezione Impermeabile Massetti Edificio - Pescara - PE | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/protezionebancodinapoli-1-scaled.jpg","datePublished":"2021-10-22T10:05:34+00:00","dateModified":"2023-10-20T15:12:17+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Protezione Impermeabile Massetti Edificio, Pescara, PE.","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/protezionebancodinapoli-1-scaled.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/protezionebancodinapoli-1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/protezione-impermeabile-massetti-edificio-pescara-pe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Protezione Impermeabile Massetti Edificio &#8211; Pescara &#8211; PE"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/9380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/15075"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=9380"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=9380"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=9380"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=9380"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=9380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}