{"id":8889,"date":"2021-10-22T10:03:00","date_gmt":"2021-10-22T10:03:00","guid":{"rendered":"https:\/\/volteco.com\/reference\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/"},"modified":"2024-05-30T12:07:50","modified_gmt":"2024-05-30T12:07:50","slug":"risanamento-ambienti-interni-villa-savorgnan-sequals-pn","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/","title":{"rendered":"Risanamento ambienti interni Villa Savorgnan &#8211; Sequals &#8211; PN"},"content":{"rendered":"","protected":false},"featured_media":14829,"template":"","scope":[1119],"problem":[919,923,1248,1247],"country":[1195,1203],"building":[35],"class_list":["post-8889","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-risanamento-umidita-murature","problem-allagamenti-soluzioni","problem-umidita-di-risalita-soluzioni","problem-allagamenti","problem-umidita-di-risalita","country-italia","country-friuli-venezia-giulia","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risanamento ambienti interni Villa Savorgnan - Sequals - PN | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento ambienti interni Villa Savorgnan, Sequals, PN.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risanamento ambienti interni Villa Savorgnan - Sequals - PN | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento ambienti interni Villa Savorgnan, Sequals, PN.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T12:07:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/fewrwege.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/\",\"name\":\"Risanamento ambienti interni Villa Savorgnan - Sequals - PN | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fewrwege.jpg\",\"datePublished\":\"2021-10-22T10:03:00+00:00\",\"dateModified\":\"2024-05-30T12:07:50+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento ambienti interni Villa Savorgnan, Sequals, PN.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fewrwege.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fewrwege.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Risanamento ambienti interni Villa Savorgnan &#8211; Sequals &#8211; PN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risanamento ambienti interni Villa Savorgnan - Sequals - PN | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento ambienti interni Villa Savorgnan, Sequals, PN.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/","og_locale":"it_IT","og_type":"article","og_title":"Risanamento ambienti interni Villa Savorgnan - Sequals - PN | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento ambienti interni Villa Savorgnan, Sequals, PN.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2024-05-30T12:07:50+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/fewrwege.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/","name":"Risanamento ambienti interni Villa Savorgnan - Sequals - PN | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/fewrwege.jpg","datePublished":"2021-10-22T10:03:00+00:00","dateModified":"2024-05-30T12:07:50+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento ambienti interni Villa Savorgnan, Sequals, PN.","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/fewrwege.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/fewrwege.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-ambienti-interni-villa-savorgnan-sequals-pn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Risanamento ambienti interni Villa Savorgnan &#8211; Sequals &#8211; PN"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/8889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/14829"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=8889"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=8889"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=8889"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=8889"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=8889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}