{"id":7640,"date":"2021-10-22T09:55:59","date_gmt":"2021-10-22T09:55:59","guid":{"rendered":"https:\/\/volteco.com\/reference\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/"},"modified":"2022-11-29T16:10:09","modified_gmt":"2022-11-29T16:10:09","slug":"rifacimento-facciata-abitazione-privata-casoli-di-atri-te","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/","title":{"rendered":"Rifacimento facciata abitazione privata &#8211; Casoli di Atri &#8211; TE"},"content":{"rendered":"","protected":false},"featured_media":14005,"template":"","scope":[1120],"problem":[918,1139],"country":[1195,1205],"building":[35],"class_list":["post-7640","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-ripristino-e-protezione-facciate","problem-muffe-soluzioni","problem-efflorescenze-muffe-alghe-e-funghi","country-italia","country-abruzzo","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rifacimento facciata abitazione privata - Casoli di Atri - TE | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata abitazione privata, Casoli di Atri, TE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifacimento facciata abitazione privata - Casoli di Atri - TE | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata abitazione privata, Casoli di Atri, TE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T16:10:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/13_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/\",\"name\":\"Rifacimento facciata abitazione privata - Casoli di Atri - TE | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/13_5.jpg\",\"datePublished\":\"2021-10-22T09:55:59+00:00\",\"dateModified\":\"2022-11-29T16:10:09+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata abitazione privata, Casoli di Atri, TE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/13_5.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/13_5.jpg\",\"width\":800,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rifacimento facciata abitazione privata &#8211; Casoli di Atri &#8211; TE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rifacimento facciata abitazione privata - Casoli di Atri - TE | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata abitazione privata, Casoli di Atri, TE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/","og_locale":"it_IT","og_type":"article","og_title":"Rifacimento facciata abitazione privata - Casoli di Atri - TE | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata abitazione privata, Casoli di Atri, TE.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-11-29T16:10:09+00:00","og_image":[{"width":800,"height":688,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/13_5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/","name":"Rifacimento facciata abitazione privata - Casoli di Atri - TE | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/13_5.jpg","datePublished":"2021-10-22T09:55:59+00:00","dateModified":"2022-11-29T16:10:09+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata abitazione privata, Casoli di Atri, TE.","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/13_5.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/13_5.jpg","width":800,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/rifacimento-facciata-abitazione-privata-casoli-di-atri-te\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Rifacimento facciata abitazione privata &#8211; Casoli di Atri &#8211; TE"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/7640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/14005"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=7640"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=7640"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=7640"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=7640"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=7640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}