{"id":7475,"date":"2021-10-22T09:54:50","date_gmt":"2021-10-22T09:54:50","guid":{"rendered":"https:\/\/volteco.com\/reference\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/"},"modified":"2022-09-12T09:15:09","modified_gmt":"2022-09-12T09:15:09","slug":"impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/","title":{"rendered":"Impermeabilizzazione e sigillatura vasca antincendio industriale &#8211; La Loggia &#8211; TO"},"content":{"rendered":"","protected":false},"featured_media":12734,"template":"","scope":[1116],"problem":[922,1135,1123],"country":[1195,1198],"building":[33],"class_list":["post-7475","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-piscine-e-vasche","problem-infiltrazioni-soluzioni","problem-perdite-dacqua","problem-infiltrazioni-dacqua-di-falda","country-italia","country-piemonte","building-industriale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione e sigillatura vasca antincendio industriale - La Loggia - TO | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione e sigillatura vasca antincendio industriale, La Loggia, TO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione e sigillatura vasca antincendio industriale - La Loggia - TO | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione e sigillatura vasca antincendio industriale, La Loggia, TO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:15:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/03_15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/\",\"name\":\"Impermeabilizzazione e sigillatura vasca antincendio industriale - La Loggia - TO | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/03_15.jpg\",\"datePublished\":\"2021-10-22T09:54:50+00:00\",\"dateModified\":\"2022-09-12T09:15:09+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione e sigillatura vasca antincendio industriale, La Loggia, TO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/03_15.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/03_15.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione e sigillatura vasca antincendio industriale &#8211; La Loggia &#8211; TO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione e sigillatura vasca antincendio industriale - La Loggia - TO | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione e sigillatura vasca antincendio industriale, La Loggia, TO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione e sigillatura vasca antincendio industriale - La Loggia - TO | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione e sigillatura vasca antincendio industriale, La Loggia, TO.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-09-12T09:15:09+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/03_15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/","name":"Impermeabilizzazione e sigillatura vasca antincendio industriale - La Loggia - TO | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/03_15.jpg","datePublished":"2021-10-22T09:54:50+00:00","dateModified":"2022-09-12T09:15:09+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione e sigillatura vasca antincendio industriale, La Loggia, TO.","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/03_15.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/03_15.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-e-sigillatura-vasca-antincendio-industriale-la-loggia-to\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione e sigillatura vasca antincendio industriale &#8211; La Loggia &#8211; TO"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/7475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/12734"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=7475"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=7475"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=7475"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=7475"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=7475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}