{"id":7437,"date":"2021-10-22T09:54:50","date_gmt":"2021-10-22T09:54:50","guid":{"rendered":"https:\/\/volteco.com\/reference\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/"},"modified":"2022-09-12T09:15:12","modified_gmt":"2022-09-12T09:15:12","slug":"ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/","title":{"rendered":"Ripristino e protezione muri di recinzione complesso residenziale La Fontana &#8211; Montesilvano &#8211; PE"},"content":{"rendered":"","protected":false},"featured_media":12703,"template":"","scope":[1119],"problem":[923,1247],"country":[1195,1205],"building":[35],"class_list":["post-7437","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-risanamento-umidita-murature","problem-umidita-di-risalita-soluzioni","problem-umidita-di-risalita","country-italia","country-abruzzo","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ripristino e protezione muri di recinzione complesso residenziale La Fontana - Montesilvano - PE | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Ripristino e protezione muri di recinzione complesso residenziale La Fontana, Montesilvano, PE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ripristino e protezione muri di recinzione complesso residenziale La Fontana - Montesilvano - PE | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Ripristino e protezione muri di recinzione complesso residenziale La Fontana, Montesilvano, PE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:15:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/05_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/\",\"name\":\"Ripristino e protezione muri di recinzione complesso residenziale La Fontana - Montesilvano - PE | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/05_4.jpg\",\"datePublished\":\"2021-10-22T09:54:50+00:00\",\"dateModified\":\"2022-09-12T09:15:12+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Ripristino e protezione muri di recinzione complesso residenziale La Fontana, Montesilvano, PE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/05_4.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/05_4.jpg\",\"width\":900,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ripristino e protezione muri di recinzione complesso residenziale La Fontana &#8211; Montesilvano &#8211; PE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ripristino e protezione muri di recinzione complesso residenziale La Fontana - Montesilvano - PE | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Ripristino e protezione muri di recinzione complesso residenziale La Fontana, Montesilvano, PE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/","og_locale":"it_IT","og_type":"article","og_title":"Ripristino e protezione muri di recinzione complesso residenziale La Fontana - Montesilvano - PE | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Ripristino e protezione muri di recinzione complesso residenziale La Fontana, Montesilvano, PE.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-09-12T09:15:12+00:00","og_image":[{"width":900,"height":672,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/05_4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/","name":"Ripristino e protezione muri di recinzione complesso residenziale La Fontana - Montesilvano - PE | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/05_4.jpg","datePublished":"2021-10-22T09:54:50+00:00","dateModified":"2022-09-12T09:15:12+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Ripristino e protezione muri di recinzione complesso residenziale La Fontana, Montesilvano, PE.","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/05_4.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/05_4.jpg","width":900,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/ripristino-e-protezione-muri-di-recinzione-complesso-residenziale-la-fontana-montesilvano-pe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Ripristino e protezione muri di recinzione complesso residenziale La Fontana &#8211; Montesilvano &#8211; PE"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/7437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/12703"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=7437"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=7437"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=7437"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=7437"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=7437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}