{"id":45302,"date":"2024-01-29T11:36:00","date_gmt":"2024-01-29T11:36:00","guid":{"rendered":"https:\/\/volteco.com\/?post_type=reference&#038;p=45302"},"modified":"2024-01-29T11:36:42","modified_gmt":"2024-01-29T11:36:42","slug":"impermeabilizzazione-cantina-vitivinicola-monforte-cn","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/","title":{"rendered":"Impermeabilizzazione cantina vitivinicola &#8211; Monforte d&#8217;Alba &#8211; CN"},"content":{"rendered":"<p>Intervento di impermeabilizzazione cantina vitivinicola sita a Monforte d&#8217;Alba, in provincia di Cuneo.<\/p>\n","protected":false},"featured_media":45309,"template":"","scope":[1115],"problem":[1123,1125,1126],"country":[1198],"building":[33],"class_list":["post-45302","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-ambienti-interrati","problem-infiltrazioni-dacqua-di-falda","problem-infiltrazioni-nei-locali-tecnici","problem-tubi-non-sigillati","country-piemonte","building-industriale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione cantina vitivinicola - Monforte d&#039;Alba - CN | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione cantina vitivinicola - Monforte d&#039;Alba - CN | Volteco\" \/>\n<meta property=\"og:description\" content=\"Intervento di impermeabilizzazione cantina vitivinicola sita a Monforte d&#8217;Alba, in provincia di Cuneo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T11:36:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2024\/01\/04-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/\",\"name\":\"Impermeabilizzazione cantina vitivinicola - Monforte d'Alba - CN | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/04-7.jpg\",\"datePublished\":\"2024-01-29T11:36:00+00:00\",\"dateModified\":\"2024-01-29T11:36:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/04-7.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/04-7.jpg\",\"width\":900,\"height\":676,\"caption\":\"Impermeabilizzazione_cantina_vitivinicola_con_soluzioni_Volteco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione cantina vitivinicola &#8211; Monforte d&#8217;Alba &#8211; CN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione cantina vitivinicola - Monforte d'Alba - CN | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione cantina vitivinicola - Monforte d'Alba - CN | Volteco","og_description":"Intervento di impermeabilizzazione cantina vitivinicola sita a Monforte d&#8217;Alba, in provincia di Cuneo.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2024-01-29T11:36:42+00:00","og_image":[{"width":900,"height":676,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2024\/01\/04-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/","name":"Impermeabilizzazione cantina vitivinicola - Monforte d'Alba - CN | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2024\/01\/04-7.jpg","datePublished":"2024-01-29T11:36:00+00:00","dateModified":"2024-01-29T11:36:42+00:00","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2024\/01\/04-7.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2024\/01\/04-7.jpg","width":900,"height":676,"caption":"Impermeabilizzazione_cantina_vitivinicola_con_soluzioni_Volteco"},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-cantina-vitivinicola-monforte-cn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione cantina vitivinicola &#8211; Monforte d&#8217;Alba &#8211; CN"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/45302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/45309"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=45302"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=45302"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=45302"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=45302"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=45302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}