{"id":37828,"date":"2022-11-22T11:51:51","date_gmt":"2022-11-22T11:51:51","guid":{"rendered":"https:\/\/volteco.com\/?post_type=reference&#038;p=37828"},"modified":"2022-11-25T08:14:20","modified_gmt":"2022-11-25T08:14:20","slug":"impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/","title":{"rendered":"Impermeabilizzazione sottopasso pedonale ferrovia &#8211; Gioia del Colle &#8211; BA"},"content":{"rendered":"<p>Intervento di impermeabilizzazione sottopasso pedonale delle Ferrovie dello Stato a Gioia del Colle, in provincia di Bari.<\/p>\n","protected":false},"featured_media":37870,"template":"","scope":[1115],"problem":[919,1248,1122,1123],"country":[1201],"building":[34],"class_list":["post-37828","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-ambienti-interrati","problem-allagamenti-soluzioni","problem-allagamenti","problem-infiltrazioni-dacqua","problem-infiltrazioni-dacqua-di-falda","country-puglia","building-pubblico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione sottopasso pedonale ferrovia - Gioia del Colle - BA | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione sottopasso pedonale ferrovia - Gioia del Colle - BA | Volteco\" \/>\n<meta property=\"og:description\" content=\"Intervento di impermeabilizzazione sottopasso pedonale delle Ferrovie dello Stato a Gioia del Colle, in provincia di Bari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T08:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/11\/03-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/\",\"name\":\"Impermeabilizzazione sottopasso pedonale ferrovia - Gioia del Colle - BA | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/03-2.jpeg\",\"datePublished\":\"2022-11-22T11:51:51+00:00\",\"dateModified\":\"2022-11-25T08:14:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/03-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/03-2.jpeg\",\"width\":675,\"height\":900,\"caption\":\"posa amphibia di volteco su sottopasso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione sottopasso pedonale ferrovia &#8211; Gioia del Colle &#8211; BA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione sottopasso pedonale ferrovia - Gioia del Colle - BA | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione sottopasso pedonale ferrovia - Gioia del Colle - BA | Volteco","og_description":"Intervento di impermeabilizzazione sottopasso pedonale delle Ferrovie dello Stato a Gioia del Colle, in provincia di Bari.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-11-25T08:14:20+00:00","og_image":[{"width":675,"height":900,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/11\/03-2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/","name":"Impermeabilizzazione sottopasso pedonale ferrovia - Gioia del Colle - BA | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/11\/03-2.jpeg","datePublished":"2022-11-22T11:51:51+00:00","dateModified":"2022-11-25T08:14:20+00:00","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/11\/03-2.jpeg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/11\/03-2.jpeg","width":675,"height":900,"caption":"posa amphibia di volteco su sottopasso"},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-sottopasso-pedonale-ferrovia-gioia-del-colle-ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione sottopasso pedonale ferrovia &#8211; Gioia del Colle &#8211; BA"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/37828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/37870"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=37828"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=37828"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=37828"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=37828"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=37828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}