{"id":36308,"date":"2022-08-23T09:27:54","date_gmt":"2022-08-23T09:27:54","guid":{"rendered":"https:\/\/volteco.com\/?post_type=reference&#038;p=36308"},"modified":"2022-09-12T09:06:28","modified_gmt":"2022-09-12T09:06:28","slug":"impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/","title":{"rendered":"Impermeabilizzazione ampliamento abitazione &#8211; Zgornja Kungota &#8211; Slovenia"},"content":{"rendered":"<p>Intervento di impermeabilizzazione ampliamento abitazione a Zgornja Kungota in Slovenia.<\/p>\n","protected":false},"featured_media":36310,"template":"","scope":[1115],"problem":[1123],"country":[1214],"building":[35],"class_list":["post-36308","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-ambienti-interrati","problem-infiltrazioni-dacqua-di-falda","country-slovenia","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione ampliamento abitazione - Zgornja Kungota - Slovenia | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione ampliamento abitazione - Zgornja Kungota - Slovenia | Volteco\" \/>\n<meta property=\"og:description\" content=\"Intervento di impermeabilizzazione ampliamento abitazione a Zgornja Kungota in Slovenia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:06:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/08\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/\",\"name\":\"Impermeabilizzazione ampliamento abitazione - Zgornja Kungota - Slovenia | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg\",\"datePublished\":\"2022-08-23T09:27:54+00:00\",\"dateModified\":\"2022-09-12T09:06:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg\",\"width\":675,\"height\":900,\"caption\":\"impermeabilizzazione con amphibia abitazione slovenia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione ampliamento abitazione &#8211; Zgornja Kungota &#8211; Slovenia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione ampliamento abitazione - Zgornja Kungota - Slovenia | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione ampliamento abitazione - Zgornja Kungota - Slovenia | Volteco","og_description":"Intervento di impermeabilizzazione ampliamento abitazione a Zgornja Kungota in Slovenia.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-09-12T09:06:28+00:00","og_image":[{"width":675,"height":900,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/08\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/","name":"Impermeabilizzazione ampliamento abitazione - Zgornja Kungota - Slovenia | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/08\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg","datePublished":"2022-08-23T09:27:54+00:00","dateModified":"2022-09-12T09:06:28+00:00","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/08\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/08\/impermeabilizzazione-con-amphibia-abitazione-slovenia.jpg","width":675,"height":900,"caption":"impermeabilizzazione con amphibia abitazione slovenia"},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/impermeabilizzazione-ampliamento-abitazione-zgornja-kungota-slovenia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione ampliamento abitazione &#8211; Zgornja Kungota &#8211; Slovenia"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/36308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/36310"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=36308"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=36308"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=36308"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=36308"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=36308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}