{"id":31539,"date":"2022-06-17T12:31:42","date_gmt":"2022-06-17T12:31:42","guid":{"rendered":"https:\/\/volteco.com\/?post_type=reference&#038;p=31539"},"modified":"2022-09-12T09:06:42","modified_gmt":"2022-09-12T09:06:42","slug":"risanamento-murature-interne-abitazione-milano-mi","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/","title":{"rendered":"Risanamento murature interne abitazione &#8211; Limbiate &#8211; MI"},"content":{"rendered":"<p>Intervento di risanamento e deumidificazione di una abitazione in provincia di Milano.<\/p>\n","protected":false},"featured_media":31543,"template":"","scope":[1119],"problem":[923,1247],"country":[1195,1197],"building":[35],"class_list":["post-31539","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-risanamento-umidita-murature","problem-umidita-di-risalita-soluzioni","problem-umidita-di-risalita","country-italia","country-lombardia","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risanamento murature interne abitazione - Limbiate - MI | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne abitazione, Limbiate, MI.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risanamento murature interne abitazione - Limbiate - MI | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne abitazione, Limbiate, MI.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/06\/02.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/\",\"name\":\"Risanamento murature interne abitazione - Limbiate - MI | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/02.jpeg\",\"datePublished\":\"2022-06-17T12:31:42+00:00\",\"dateModified\":\"2022-09-12T09:06:42+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne abitazione, Limbiate, MI.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/02.jpeg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/02.jpeg\",\"width\":900,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/risanamento-murature-interne-abitazione-milano-mi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/referenze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Risanamento murature interne abitazione &#8211; Limbiate &#8211; MI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risanamento murature interne abitazione - Limbiate - MI | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne abitazione, Limbiate, MI.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/","og_locale":"it_IT","og_type":"article","og_title":"Risanamento murature interne abitazione - Limbiate - MI | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne abitazione, Limbiate, MI.","og_url":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-09-12T09:06:42+00:00","og_image":[{"width":900,"height":405,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/06\/02.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/","url":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/","name":"Risanamento murature interne abitazione - Limbiate - MI | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/06\/02.jpeg","datePublished":"2022-06-17T12:31:42+00:00","dateModified":"2022-09-12T09:06:42+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento murature interne abitazione, Limbiate, MI.","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/06\/02.jpeg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2022\/06\/02.jpeg","width":900,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/it\/referenze\/risanamento-murature-interne-abitazione-milano-mi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/staging.volteco.com\/it\/referenze\/"},{"@type":"ListItem","position":3,"name":"Risanamento murature interne abitazione &#8211; Limbiate &#8211; MI"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/it\/#website","url":"https:\/\/staging.volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/staging.volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference\/31539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media\/31543"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/media?parent=31539"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/scope?post=31539"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/problem?post=31539"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/country?post=31539"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/it\/wp-json\/wp\/v2\/building?post=31539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}