{"id":25824,"date":"2021-10-22T09:56:52","date_gmt":"2021-10-22T09:56:52","guid":{"rendered":"https:\/\/volteco.com\/referenze\/deumidificazione-e-risanamento-intonaci-abitazione-privata-sacile-pn"},"modified":"2024-04-10T15:26:53","modified_gmt":"2024-04-10T15:26:53","slug":"dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/","title":{"rendered":"Dehumidification of damp walls &#8211; Sacile &#8211; Friuli-Venezia Giulia"},"content":{"rendered":"","protected":false},"featured_media":17436,"template":"","scope":[1348],"problem":[1342,1341,1363,1345,1347],"country":[1430,1438],"building":[1392],"class_list":["post-25824","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-dehumidification-of-damp-walls","problem-rising-dampness","problem-deterioration-solutions","problem-wet-and-damp-walls","problem-deterioration-of-the-walls","problem-rising-damp","country-italy","country-friuli-venezia-giulia-en","building-residential"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dehumidification of damp walls - Sacile - Friuli-Venezia Giulia | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dehumidification of damp walls - Sacile - Friuli-Venezia Giulia | Volteco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T15:26:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/\",\"name\":\"Dehumidification of damp walls - Sacile - Friuli-Venezia Giulia | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/35.jpg\",\"datePublished\":\"2021-10-22T09:56:52+00:00\",\"dateModified\":\"2024-04-10T15:26:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/35.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/35.jpg\",\"width\":672,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dehumidification of damp walls &#8211; Sacile &#8211; Friuli-Venezia Giulia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/\",\"name\":\"Volteco\",\"description\":\"Waterproofing products\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dehumidification of damp walls - Sacile - Friuli-Venezia Giulia | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/","og_locale":"en_US","og_type":"article","og_title":"Dehumidification of damp walls - Sacile - Friuli-Venezia Giulia | Volteco","og_url":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2024-04-10T15:26:53+00:00","og_image":[{"width":672,"height":900,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/35.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/","url":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/","name":"Dehumidification of damp walls - Sacile - Friuli-Venezia Giulia | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/35.jpg","datePublished":"2021-10-22T09:56:52+00:00","dateModified":"2024-04-10T15:26:53+00:00","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/35.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/35.jpg","width":672,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/en\/references\/dehumidification-of-damp-walls-sacile-friuli-venezia-giulia-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/en\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/staging.volteco.com\/en\/references\/"},{"@type":"ListItem","position":3,"name":"Dehumidification of damp walls &#8211; Sacile &#8211; Friuli-Venezia Giulia"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/en\/#website","url":"https:\/\/staging.volteco.com\/en\/","name":"Volteco","description":"Waterproofing products","publisher":{"@id":"https:\/\/staging.volteco.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/en\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.volteco.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/reference\/25824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/media\/17436"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/media?parent=25824"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/scope?post=25824"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/problem?post=25824"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/country?post=25824"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/building?post=25824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}