{"id":24717,"date":"2021-10-22T10:03:39","date_gmt":"2021-10-22T10:03:39","guid":{"rendered":"https:\/\/volteco.com\/referenze\/impermeabilizzazione-nuova-costruzione-interrata-barcellona-spagna"},"modified":"2024-05-30T12:19:24","modified_gmt":"2024-05-30T12:19:24","slug":"waterproofing-of-basements-barcellona-spain","status":"publish","type":"reference","link":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/","title":{"rendered":"Waterproofing of basements &#8211; Barcellona &#8211; Spain"},"content":{"rendered":"","protected":false},"featured_media":24718,"template":"","scope":[1353],"problem":[1350,1358],"country":[1463],"building":[1392],"class_list":["post-24717","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-waterproofing-of-basements","problem-infiltrations-solutions","problem-groundwater-infiltration","country-spain","building-residential"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Waterproofing of basements - Barcellona - Spain | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Waterproofing of basements - Barcellona - Spain | Volteco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T12:19:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/1794-amph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1446\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/\",\"name\":\"Waterproofing of basements - Barcellona - Spain | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1794-amph.jpg\",\"datePublished\":\"2021-10-22T10:03:39+00:00\",\"dateModified\":\"2024-05-30T12:19:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1794-amph.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1794-amph.jpg\",\"width\":1446,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/waterproofing-of-basements-barcellona-spain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Waterproofing of basements &#8211; Barcellona &#8211; Spain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/\",\"name\":\"Volteco\",\"description\":\"Waterproofing products\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/staging.volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.volteco.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Waterproofing of basements - Barcellona - Spain | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/","og_locale":"en_US","og_type":"article","og_title":"Waterproofing of basements - Barcellona - Spain | Volteco","og_url":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2024-05-30T12:19:24+00:00","og_image":[{"width":1446,"height":850,"url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/1794-amph.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/","url":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/","name":"Waterproofing of basements - Barcellona - Spain | Volteco","isPartOf":{"@id":"https:\/\/staging.volteco.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/#primaryimage"},"image":{"@id":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/1794-amph.jpg","datePublished":"2021-10-22T10:03:39+00:00","dateModified":"2024-05-30T12:19:24+00:00","breadcrumb":{"@id":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/#primaryimage","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/1794-amph.jpg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/11\/1794-amph.jpg","width":1446,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/staging.volteco.com\/en\/references\/waterproofing-of-basements-barcellona-spain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/staging.volteco.com\/en\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/staging.volteco.com\/en\/references\/"},{"@type":"ListItem","position":3,"name":"Waterproofing of basements &#8211; Barcellona &#8211; Spain"}]},{"@type":"WebSite","@id":"https:\/\/staging.volteco.com\/en\/#website","url":"https:\/\/staging.volteco.com\/en\/","name":"Volteco","description":"Waterproofing products","publisher":{"@id":"https:\/\/staging.volteco.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.volteco.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/staging.volteco.com\/en\/#organization","name":"Volteco S.p.A.","url":"https:\/\/staging.volteco.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.volteco.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/staging.volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/staging.volteco.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/reference\/24717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/media\/24718"}],"wp:attachment":[{"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/media?parent=24717"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/scope?post=24717"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/problem?post=24717"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/country?post=24717"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/staging.volteco.com\/en\/wp-json\/wp\/v2\/building?post=24717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}